
{"id":4235,"count":7,"description":"","link":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en","name":"@Roberta Sala","slug":"roberta_sala_en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roberta Sala Archives - Fondazione Giannino Bassetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"@Roberta Sala Archives - Fondazione Giannino Bassetti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giannino Bassetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/tag\\\/roberta_sala_en\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/tag\\\/roberta_sala_en\",\"name\":\"@Roberta Sala Archives - Fondazione Giannino Bassetti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/tag\\\/roberta_sala_en#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/tag\\\/roberta_sala_en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"@Roberta Sala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"name\":\"Fondazione Giannino Bassetti\",\"description\":\"Fondazione Giannino Bassetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"alternateName\":\"FGB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\",\"name\":\"Fondazione Giannino Bassetti ETS\",\"alternateName\":\"FGB\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"width\":696,\"height\":696,\"caption\":\"Fondazione Giannino Bassetti ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roberta Sala Archives - Fondazione Giannino Bassetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en","og_locale":"en_US","og_type":"article","og_title":"@Roberta Sala Archives - Fondazione Giannino Bassetti","og_url":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en","og_site_name":"Fondazione Giannino Bassetti","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en","url":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en","name":"@Roberta Sala Archives - Fondazione Giannino Bassetti","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en#website"},"breadcrumb":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionebassetti.org\/en\/tag\/roberta_sala_en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionebassetti.org\/en"},{"@type":"ListItem","position":2,"name":"@Roberta Sala"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionebassetti.org\/en#website","url":"https:\/\/www.fondazionebassetti.org\/en","name":"Fondazione Giannino Bassetti","description":"Fondazione Giannino Bassetti","publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"alternateName":"FGB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionebassetti.org\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazionebassetti.org\/en#organization","name":"Fondazione Giannino Bassetti ETS","alternateName":"FGB","url":"https:\/\/www.fondazionebassetti.org\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","width":696,"height":696,"caption":"Fondazione Giannino Bassetti ETS"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/tags\/4235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts?tags=4235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}