
{"id":30558,"date":"2023-03-30T19:43:19","date_gmt":"2023-03-30T17:43:19","guid":{"rendered":"https:\/\/www.fondazionebassetti.org\/_da_sistemare_it\/2023\/03\/curare_linvecchiamento_4_4"},"modified":"2023-12-03T18:03:54","modified_gmt":"2023-12-03T17:03:54","slug":"curare_linvecchiamento_4_4","status":"publish","type":"post","link":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4","title":{"rendered":"Curare l&#8217;invecchiamento? &#8211; 4\/4"},"content":{"rendered":"<p><div class=\"embeddedVideoFluid\">    <iframe src=\"https:\/\/player.vimeo.com\/video\/819780638\" frameborder=\"0\" class=\"allowfullscreen\"><\/iframe><\/div>\n<p><em>Event<\/em>: <strong>Curare l&#8217;invecchiamento?<\/strong>.<br \/><em>Date<\/em>: 2023 03 30<br \/><em>Time<\/em>: 31:10 min.<br \/><em>Place<\/em>: Fondazione Giannino Bassetti, Milano.<br \/><em>Language<\/em>: Italiano.<br \/><em>Part<\/em>: 4\/4<br \/><em>url Vimeo<\/em>: <a href=\"https:\/\/vimeo.com\/819780638\" title=\"FGB on Vimeo\">https:\/\/vimeo.com\/819780638<\/a><br \/><em>Photos<\/em>: <a href=\"https:\/\/www.flickr.com\/photos\/fondazionebassetti\/albums\/72177720307266373\" title=\"FGB on Flickr\">Album in Flickr<\/a> e post in Instagram <a href=\"https:\/\/www.instagram.com\/p\/CriqjrWISGC\/\" title=\"FGB in Instagram\">1<\/a>, <a href=\"https:\/\/www.instagram.com\/p\/CrirOWVIaXr\/\" title=\"FGB in Instagram\">2<\/a>, <a href=\"https:\/\/www.instagram.com\/p\/CrirrM3oXJM\/\" title=\"FGB in Instagram\">3<\/a>, <a href=\"https:\/\/www.instagram.com\/p\/CriscJ-IbiS\/\" title=\"FGB in Instagram\">4<\/a>, <a href=\"https:\/\/www.instagram.com\/p\/CrisyAgom-E\/\" title=\"FGB in Instagram\">5<\/a><!--...-->.<br \/><em>Podcast<\/em>: la <a href=\"https:\/\/anchor.fm\/fondazione-giannino-bassetti\/episodes\/Curare-linvecchiamento----44-e22pcb7\" title=\"Anchor FM - I Dialoghi di Fondazione Bassetti\">singola parte<\/a> 1 di 3, la <a href=\"https:\/\/anchor.fm\/fondazione-giannino-bassetti\/episodes\/Curare-linvecchiamento----Versione-integrale-e22pcdr\" title=\"Anchor FM - I Dialoghi di Fondazione Bassetti\">versione integrale<\/a> e la <a href=\"https:\/\/open.spotify.com\/playlist\/3zv2FIOaxC2lEyNo6f98RR?si=946ad3205f5b45a7\" title=\"Spotify\">playlist (in Spotify)<\/a><br \/><em>Post<\/em>: <a href=\"\/it\/focus\/2023\/04\/curare_linvecchiamento.html\" title=\"FGB Focus\">Curare l&#8217;invecchiamento?<\/a>.<\/p>\n<p><em>Contents<\/em>: <\/p>\n<p><em>Interventi di<\/em><br \/><strong>Felice Scalvini<\/strong>, presidente Fondazione Ravasi Garzanti<br \/><strong>Claudio Vernieri<\/strong>, IFOM e Istituto Nazionale dei Tumori<br \/><strong>Giuseppe Bellelli<\/strong>, Universit\u00e0 Milano Bicocca<br \/><strong>Piero Bassetti<\/strong>, presidente Fondazione Giannino Bassetti<br \/><strong>Fabrizio d&#8217;Adda di Fagagna<\/strong>, IFOM e CNR<\/p>\n<p>Il 30 marzo 2023, per il quarto appuntamento del ciclo <a href=\"https:\/\/www.fondazionebassetti.org\/tag\/longevita_e_innovazione\" title=\"FGB Tag - Longevit\u00e0 e innovazione\">Longevit\u00e0 e Innovazione<\/a>, abbiamo ospitato il seminario <a href=\"\/it\/segnalazioni\/2023\/03\/curare_linvecchiamento_nuovo_d.html\" title=\"FGB News\">Curare l&#8217;invecchiamento?<\/a> All&#8217;incontro, organizzato in partnership con <a href=\"https:\/\/fondazioneravasi-garzanti.org\/\" title=\"Fondazione Ravasi Garzanti\">Fondazione Ravasi Garzanti<\/a>, ha collaborato l&#8217;<a href=\"https:\/\/www.ifom.eu\/it\/\" title=\"IFOM - Istituto Fondazione di Oncologia Molecolare\">Istituto Fondazione di Oncologia Molecolare<\/a> (<strong>IFOM<\/strong>). Con la moderazione di Francesco Samore\u0300, segretario generale di Fondazione Bassetti, e alla presenza del presidente Piero Bassetti, hanno partecipato: Elisabetta Donati, responsabile della Segreteria Scientifica di Fondazione Ravasi-Garzanti, il geriatra dell&#8217;Universit\u00e0 Milano Bicocca Giuseppe Bellelli, i ricercatori IFOM Fabrizio d&#8217;Adda di Fagagna e Claudio Vernieri, e la bioeticista Virginia Sanchini.<\/p>\n<p>Parte 4 di 4<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class='image'><a href='\/en\/video\/2023\/03\/curare_linvecchiamento_-_44.html'><img src='\/it\/focus\/img\/Cura-invecchi-130.jpg' width='130' height='130' border='0' alt='Curare l'invecchiamento? - 4\/4' title='Curare l'invecchiamento? - 4\/4' \/><\/a><\/div>\n<div class='info'>\n<div class='vedianche'>Vedi anche: tutti i seminari del ciclo <a href=\"https:\/\/www.fondazionebassetti.org\/tag\/longevita_e_innovazione\" title=\"FGB Tag - Longevit\u00e0 e Innovazione\">Longevit\u00e0 e Innovazione<\/a> e i materiali del corso al Politecnico <a href='\/it\/focus\/2021\/05\/longevita_e_innovazione_respon.html' title='FGB Focus'>Longevit\u00e0 e innovazione responsabile<\/a><\/div>\n<\/p><\/div>\n","protected":false},"author":19,"featured_media":30559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[1418],"tags":[5568,5567,5548,5565,1323,1625,2338,5566,1591,3720,5547,1554,1798],"class_list":["post-30558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video","tag-claudio_vernieri","tag-fabrizio_dadda_di_fagagna","tag-felice_scalvini","tag-giuseppe_bellelli","tag-piero_bassetti","tag-antropologia","tag-cura","tag-curare_linvecchiamento","tag-health","tag-longevita","tag-longevita_e_innovazione","tag-policy","tag-sociologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curare l&#039;invecchiamento? - 4\/4 - Fondazione Giannino Bassetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curare l&#039;invecchiamento? - 4\/4 - Fondazione Giannino Bassetti\" \/>\n<meta property=\"og:description\" content=\"Vedi anche: tutti i seminari del ciclo Longevit\u00e0 e Innovazione e i materiali del corso al Politecnico Longevit\u00e0 e innovazione responsabile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giannino Bassetti\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-30T17:43:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-03T17:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione FGB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione FGB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4\"},\"author\":{\"name\":\"Redazione FGB\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/person\\\/afc79f410c72338ff829d54ba15987e7\"},\"headline\":\"Curare l&#8217;invecchiamento? &#8211; 4\\\/4\",\"datePublished\":\"2023-03-30T17:43:19+00:00\",\"dateModified\":\"2023-12-03T17:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4\"},\"wordCount\":177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/9285_Cura-invecchi-130.png\",\"keywords\":[\"@Claudio Vernieri\",\"@Fabrizio d'Adda di Fagagna\",\"@Felice Scalvini\",\"@Giuseppe Bellelli\",\"@Piero Bassetti\",\"antropologia\",\"cura\",\"Curare l'invecchiamento?\",\"health\",\"longevit\u00e0\",\"longevit\u00e0 e innovazione\",\"policy\",\"sociologia\"],\"articleSection\":[\"Video\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4\",\"name\":\"Curare l'invecchiamento? - 4\\\/4 - Fondazione Giannino Bassetti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/9285_Cura-invecchi-130.png\",\"datePublished\":\"2023-03-30T17:43:19+00:00\",\"dateModified\":\"2023-12-03T17:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/9285_Cura-invecchi-130.png\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/9285_Cura-invecchi-130.png\",\"width\":1024,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2023\\\/03\\\/curare_linvecchiamento_4_4#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curare l&#8217;invecchiamento? &#8211; 4\\\/4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"name\":\"Fondazione Giannino Bassetti\",\"description\":\"Fondazione Giannino Bassetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"alternateName\":\"FGB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\",\"name\":\"Fondazione Giannino Bassetti ETS\",\"alternateName\":\"FGB\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"width\":696,\"height\":696,\"caption\":\"Fondazione Giannino Bassetti ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/person\\\/afc79f410c72338ff829d54ba15987e7\",\"name\":\"Redazione FGB\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/author\\\/redazione_fgb\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curare l'invecchiamento? - 4\/4 - Fondazione Giannino Bassetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4","og_locale":"en_US","og_type":"article","og_title":"Curare l'invecchiamento? - 4\/4 - Fondazione Giannino Bassetti","og_description":"Vedi anche: tutti i seminari del ciclo Longevit\u00e0 e Innovazione e i materiali del corso al Politecnico Longevit\u00e0 e innovazione responsabile","og_url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4","og_site_name":"Fondazione Giannino Bassetti","article_published_time":"2023-03-30T17:43:19+00:00","article_modified_time":"2023-12-03T17:03:54+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png","type":"image\/png"}],"author":"Redazione FGB","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione FGB","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#article","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4"},"author":{"name":"Redazione FGB","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/person\/afc79f410c72338ff829d54ba15987e7"},"headline":"Curare l&#8217;invecchiamento? &#8211; 4\/4","datePublished":"2023-03-30T17:43:19+00:00","dateModified":"2023-12-03T17:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4"},"wordCount":177,"commentCount":0,"publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png","keywords":["@Claudio Vernieri","@Fabrizio d'Adda di Fagagna","@Felice Scalvini","@Giuseppe Bellelli","@Piero Bassetti","antropologia","cura","Curare l'invecchiamento?","health","longevit\u00e0","longevit\u00e0 e innovazione","policy","sociologia"],"articleSection":["Video"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4","url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4","name":"Curare l'invecchiamento? - 4\/4 - Fondazione Giannino Bassetti","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#primaryimage"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png","datePublished":"2023-03-30T17:43:19+00:00","dateModified":"2023-12-03T17:03:54+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#primaryimage","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/05\/9285_Cura-invecchi-130.png","width":1024,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2023\/03\/curare_linvecchiamento_4_4#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionebassetti.org\/en"},{"@type":"ListItem","position":2,"name":"Curare l&#8217;invecchiamento? &#8211; 4\/4"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionebassetti.org\/en#website","url":"https:\/\/www.fondazionebassetti.org\/en","name":"Fondazione Giannino Bassetti","description":"Fondazione Giannino Bassetti","publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"alternateName":"FGB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionebassetti.org\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazionebassetti.org\/en#organization","name":"Fondazione Giannino Bassetti ETS","alternateName":"FGB","url":"https:\/\/www.fondazionebassetti.org\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","width":696,"height":696,"caption":"Fondazione Giannino Bassetti ETS"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/person\/afc79f410c72338ff829d54ba15987e7","name":"Redazione FGB","url":"https:\/\/www.fondazionebassetti.org\/en\/author\/redazione_fgb"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/30558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/comments?post=30558"}],"version-history":[{"count":7,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/30558\/revisions"}],"predecessor-version":[{"id":32752,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/30558\/revisions\/32752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media\/30559"}],"wp:attachment":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media?parent=30558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/categories?post=30558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/tags?post=30558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}