
{"id":19291,"date":"2013-05-09T11:50:34","date_gmt":"2013-05-09T09:50:34","guid":{"rendered":"https:\/\/www.fondazionebassetti.org\/non-categorizzato\/2013\/05\/neuroetica_nascita_di_una_disc_11"},"modified":"2013-05-09T11:50:34","modified_gmt":"2013-05-09T09:50:34","slug":"neuroetica_nascita_di_una_disc_11","status":"publish","type":"post","link":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11","title":{"rendered":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana &#8211; 12\/22"},"content":{"rendered":"<p><em>Event<\/em>: Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana.<br \/>\n<em>Title<\/em>: Biology and Ethics.<br \/>\n<em>Date<\/em>: 2013 05 09<br \/>\n<em>Time<\/em>: 31 min.<br \/>\n<em>Place<\/em>: Palazzo del Bo, Padova, Italy.<br \/>\n<em>Language<\/em>: English.<br \/>\n<em>url Vimeo<\/em>: <a href=\"http:\/\/vimeo.com\/67292478\" title=\"FGB on Vimeo\">http:\/\/vimeo.com\/67292478<\/a><br \/>\n<em>Report<\/em>: <a href=\"archi_vivo\/2013\/07\/neuroetica_nascita_di_una_disc\" title=\"FGB Focus\">Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana<\/a>.<\/p>\n<p><strong>Neuroetica 2013.<\/strong><br \/>\nNeuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana.<br \/>\nConvegno Scientifico Internazionale di Neuroetica.<br \/>\nPadova, Palazzo del Bo, Aula Nievo.<br \/>\n8-10 maggio 2013<\/p>\n<p>Universit\u00e0 degli Studi di Padova<br \/>\ncon il sostegno di<br \/>\nFondazione Giannino Bassetti<br \/>\nFondazione Sigma Tau.<\/p>\n<p><strong>Parte 10 di 22<\/strong><br \/>\n<em>9 maggio 2013<\/em><br \/>\nSession: Debates in Neuroethics &#8211; Ethics and Biology<br \/>\nChairperson: <strong>Massimo Reichlin<\/strong>, Universit\u00e0 Vita-Salute San Raffaele, Milano<\/p>\n<p><strong>Michele Di Francesco<\/strong>, Universit\u00e0 Vita-Salute San Raffaele, Milano<br \/>\n&#8220;Biology and Ethics&#8221;<\/p>\n<div class=\"embeddedVideoFluid\"> <iframe src=\"https:\/\/player.vimeo.com\/video\/67292478\" frameborder=\"0\" class=\"allowfullscreen\"><\/iframe><\/div>\n<p>&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"image\"><a href=\"\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11.html\"><img loading=\"lazy\" decoding=\"async\" src=\"\/en\/video\/img\/FGB-video-standard-2013_130.jpg\" width=\"130\" height=\"130\" border=\"0\" alt=\"FGB video\" title=\"FGB video\" \/><\/a><\/div>\n<div class=\"info\">\n<div class=\"linklingua\"><!-- --><\/div>\n<\/div>\n","protected":false},"author":16,"featured_media":24208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[3054,3044,1418],"tags":[4714,4131,3927,4046,4049,3926,4835,4130],"class_list":["post-19291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convegno_scientifico_internazi","category-neuroetica_nascita_di_una_disc","category-video","tag-michele_di_francesco_en","tag-empatia_en","tag-neuroethics_en","tag-neuroscience_en","tag-neuroscienze_en","tag-responsibility_en","tag-socializzazione_en","tag-sociologia_en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\/22 - Fondazione Giannino Bassetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\/22 - Fondazione Giannino Bassetti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giannino Bassetti\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-09T09:50:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tommaso Correale Santacroce\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11\"},\"author\":{\"name\":\"FGB\"},\"headline\":\"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana &#8211; 12\\\/22\",\"datePublished\":\"2013-05-09T09:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19291_FGB-video-standard-2013_130.jpg\",\"keywords\":[\"@Michele Di Francesco\",\"empatia\",\"neuroethics\",\"neuroscience\",\"neuroscienze\",\"responsibility\",\"socializzazione\",\"sociologia\"],\"articleSection\":[\"Convegno Scientifico Internazionale di Neuroetica\",\"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana\",\"Video\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11\",\"name\":\"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\\\/22 - Fondazione Giannino Bassetti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19291_FGB-video-standard-2013_130.jpg\",\"datePublished\":\"2013-05-09T09:50:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19291_FGB-video-standard-2013_130.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19291_FGB-video-standard-2013_130.jpg\",\"width\":1024,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2013\\\/05\\\/neuroetica_nascita_di_una_disc_11#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana &#8211; 12\\\/22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"name\":\"Fondazione Giannino Bassetti\",\"description\":\"Fondazione Giannino Bassetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"alternateName\":\"FGB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\",\"name\":\"Fondazione Giannino Bassetti ETS\",\"alternateName\":\"FGB\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"width\":696,\"height\":696,\"caption\":\"Fondazione Giannino Bassetti ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/person\\\/168d0c230d9f804733495a1f3c8a758c\",\"name\":\"Tommaso Correale Santacroce\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/author\\\/tommaso_correale_santacroce\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\/22 - Fondazione Giannino Bassetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11","og_locale":"en_US","og_type":"article","og_title":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\/22 - Fondazione Giannino Bassetti","og_url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11","og_site_name":"Fondazione Giannino Bassetti","article_published_time":"2013-05-09T09:50:34+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tommaso Correale Santacroce","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#article","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11"},"author":{"name":"FGB"},"headline":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana &#8211; 12\/22","datePublished":"2013-05-09T09:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11"},"wordCount":123,"publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg","keywords":["@Michele Di Francesco","empatia","neuroethics","neuroscience","neuroscienze","responsibility","socializzazione","sociologia"],"articleSection":["Convegno Scientifico Internazionale di Neuroetica","Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana","Video"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11","url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11","name":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana - 12\/22 - Fondazione Giannino Bassetti","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#primaryimage"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg","datePublished":"2013-05-09T09:50:34+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#primaryimage","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19291_FGB-video-standard-2013_130.jpg","width":1024,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2013\/05\/neuroetica_nascita_di_una_disc_11#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionebassetti.org\/en"},{"@type":"ListItem","position":2,"name":"Neuroetica: nascita di una disciplina. Dai laboratori alla vita quotidiana &#8211; 12\/22"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionebassetti.org\/en#website","url":"https:\/\/www.fondazionebassetti.org\/en","name":"Fondazione Giannino Bassetti","description":"Fondazione Giannino Bassetti","publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"alternateName":"FGB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionebassetti.org\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazionebassetti.org\/en#organization","name":"Fondazione Giannino Bassetti ETS","alternateName":"FGB","url":"https:\/\/www.fondazionebassetti.org\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","width":696,"height":696,"caption":"Fondazione Giannino Bassetti ETS"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/person\/168d0c230d9f804733495a1f3c8a758c","name":"Tommaso Correale Santacroce","url":"https:\/\/www.fondazionebassetti.org\/en\/author\/tommaso_correale_santacroce"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/19291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/comments?post=19291"}],"version-history":[{"count":0,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/19291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media\/24208"}],"wp:attachment":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media?parent=19291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/categories?post=19291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/tags?post=19291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}