
{"id":19168,"date":"2011-05-05T15:59:29","date_gmt":"2011-05-05T13:59:29","guid":{"rendered":"https:\/\/www.fondazionebassetti.org\/non-categorizzato\/2011\/05\/le_neuroscienze_incontrano_le_12"},"modified":"2011-05-05T15:59:29","modified_gmt":"2011-05-05T13:59:29","slug":"le_neuroscienze_incontrano_le_12","status":"publish","type":"post","link":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12","title":{"rendered":"Le Neuroscienze incontrano le altre discipline &#8211; 14\/30"},"content":{"rendered":"<p><em>Event<\/em>: Le Neuroscienze incontrano le altre discipline.<br \/>\n<em>Title<\/em>: I problemi del concetto di coscienza.<br \/>\n<em>Date<\/em>: 2011 05 05<br \/>\n<em>Time<\/em>: 29 min.<br \/>\n<em>Place<\/em>: Palazzo del Bo, Padova, Italy.<br \/>\n<em>Language<\/em>: Italiano.<br \/>\n<em>url Vimeo<\/em>: <a href=\"http:\/\/vimeo.com\/24334785\" title=\"FGB on Vimeo\">http:\/\/vimeo.com\/24334785<\/a><br \/>\n<em>Report<\/em>: <a href=\"archi_vivo\/2011\/06\/neuroetica_2011_-_i_video_del\" title=\"FGB Focus\">Neuroetica 2011<\/a><\/p>\n<p>Neuroetica 2011.<br \/>\nLe Neuroscienze incontrano le altre discipline.<br \/>\nConvegno.<br \/>\nPadova, Palazzo del Bo, Aula Nievo.<br \/>\n4-6 maggio 2011<\/p>\n<p>Universit\u00e0 degli Studi di Padova<br \/>\ncon il sostegno di<br \/>\nFondazione Giannino Bassetti<br \/>\nFondazione Sigma Tau.<\/p>\n<p>parte 14 di 30<br \/>\n5 maggio 2011<br \/>\nEdoardo Boncinelli (Universita? San Raffaele, Milano)<br \/>\n&#8220;I problemi del concetto di coscienza&#8221;.<br \/>\n(registrazione dello streaming)<\/p>\n<div class=\"embeddedVideoFluid\"> <iframe src=\"https:\/\/player.vimeo.com\/video\/24334785\" frameborder=\"0\" class=\"allowfullscreen\"><\/iframe><\/div>\n<p>&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"image\"><a href=\"\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12.html\"><img loading=\"lazy\" decoding=\"async\" src=\"\/en\/video\/img\/FGB-video-standard-2011_130.jpg\" width=\"130\" height=\"130\" border=\"0\" alt=\"FGB video\" title=\"FGB video\" \/><\/a><\/div>\n<div class=\"info\">\n<div class=\"linklingua\"><!-- --><\/div>\n<\/div>\n","protected":false},"author":32,"featured_media":23962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[3054,3039,1418],"tags":[4792,4028,4006,4046,3926],"class_list":["post-19168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convegno_scientifico_internazi","category-le_neuroscienze_incontrano_le","category-video","tag-edoardo_boncinelli_en","tag-bioethics_en","tag-ethics_en","tag-neuroscience_en","tag-responsibility_en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Neuroscienze incontrano le altre discipline - 14\/30 - Fondazione Giannino Bassetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Neuroscienze incontrano le altre discipline - 14\/30 - Fondazione Giannino Bassetti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giannino Bassetti\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-05T13:59:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12\"},\"author\":{\"name\":\"user01\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/person\\\/80ec242c6858ae565552ba01d3204c0a\"},\"headline\":\"Le Neuroscienze incontrano le altre discipline &#8211; 14\\\/30\",\"datePublished\":\"2011-05-05T13:59:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12\"},\"wordCount\":89,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19168_FGB-video-standard-2011_130.jpg\",\"keywords\":[\"@Edoardo Boncinelli\",\"bioethics\",\"ethics\",\"neuroscience\",\"responsibility\"],\"articleSection\":[\"Convegno Scientifico Internazionale di Neuroetica\",\"Le Neuroscienze incontrano le altre discipline\",\"Video\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12\",\"name\":\"Le Neuroscienze incontrano le altre discipline - 14\\\/30 - Fondazione Giannino Bassetti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19168_FGB-video-standard-2011_130.jpg\",\"datePublished\":\"2011-05-05T13:59:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#primaryimage\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19168_FGB-video-standard-2011_130.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/19168_FGB-video-standard-2011_130.jpg\",\"width\":1024,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/video\\\/2011\\\/05\\\/le_neuroscienze_incontrano_le_12#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Neuroscienze incontrano le altre discipline &#8211; 14\\\/30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#website\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"name\":\"Fondazione Giannino Bassetti\",\"description\":\"Fondazione Giannino Bassetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\"},\"alternateName\":\"FGB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#organization\",\"name\":\"Fondazione Giannino Bassetti ETS\",\"alternateName\":\"FGB\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo696x696.jpg\",\"width\":696,\"height\":696,\"caption\":\"Fondazione Giannino Bassetti ETS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en#\\\/schema\\\/person\\\/80ec242c6858ae565552ba01d3204c0a\",\"name\":\"user01\",\"url\":\"https:\\\/\\\/www.fondazionebassetti.org\\\/en\\\/author\\\/user01\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Neuroscienze incontrano le altre discipline - 14\/30 - Fondazione Giannino Bassetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12","og_locale":"en_US","og_type":"article","og_title":"Le Neuroscienze incontrano le altre discipline - 14\/30 - Fondazione Giannino Bassetti","og_url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12","og_site_name":"Fondazione Giannino Bassetti","article_published_time":"2011-05-05T13:59:29+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg","type":"image\/jpeg"}],"author":"user01","twitter_card":"summary_large_image","twitter_misc":{"Written by":"user01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#article","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12"},"author":{"name":"user01","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/person\/80ec242c6858ae565552ba01d3204c0a"},"headline":"Le Neuroscienze incontrano le altre discipline &#8211; 14\/30","datePublished":"2011-05-05T13:59:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12"},"wordCount":89,"publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg","keywords":["@Edoardo Boncinelli","bioethics","ethics","neuroscience","responsibility"],"articleSection":["Convegno Scientifico Internazionale di Neuroetica","Le Neuroscienze incontrano le altre discipline","Video"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12","url":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12","name":"Le Neuroscienze incontrano le altre discipline - 14\/30 - Fondazione Giannino Bassetti","isPartOf":{"@id":"https:\/\/www.fondazionebassetti.org\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#primaryimage"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg","datePublished":"2011-05-05T13:59:29+00:00","breadcrumb":{"@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#primaryimage","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2022\/06\/19168_FGB-video-standard-2011_130.jpg","width":1024,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazionebassetti.org\/en\/video\/2011\/05\/le_neuroscienze_incontrano_le_12#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazionebassetti.org\/en"},{"@type":"ListItem","position":2,"name":"Le Neuroscienze incontrano le altre discipline &#8211; 14\/30"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazionebassetti.org\/en#website","url":"https:\/\/www.fondazionebassetti.org\/en","name":"Fondazione Giannino Bassetti","description":"Fondazione Giannino Bassetti","publisher":{"@id":"https:\/\/www.fondazionebassetti.org\/en#organization"},"alternateName":"FGB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazionebassetti.org\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fondazionebassetti.org\/en#organization","name":"Fondazione Giannino Bassetti ETS","alternateName":"FGB","url":"https:\/\/www.fondazionebassetti.org\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/","url":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","contentUrl":"https:\/\/www.fondazionebassetti.org\/wp-content\/uploads\/2025\/09\/logo696x696.jpg","width":696,"height":696,"caption":"Fondazione Giannino Bassetti ETS"},"image":{"@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fondazionebassetti.org\/en#\/schema\/person\/80ec242c6858ae565552ba01d3204c0a","name":"user01","url":"https:\/\/www.fondazionebassetti.org\/en\/author\/user01"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/19168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/comments?post=19168"}],"version-history":[{"count":0,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/posts\/19168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media\/23962"}],"wp:attachment":[{"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/media?parent=19168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/categories?post=19168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazionebassetti.org\/en\/wp-json\/wp\/v2\/tags?post=19168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}